{"id":3778,"date":"2016-05-25T11:55:06","date_gmt":"2016-05-25T11:55:06","guid":{"rendered":"http:\/\/www.clinica-picasso.eu\/es\/medizinischer-check-up-mallorca\/orthopadie-check-up\/"},"modified":"2026-05-07T11:20:42","modified_gmt":"2026-05-07T09:20:42","slug":"ortopedia-y-traumatologia","status":"publish","type":"page","link":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/","title":{"rendered":"CHEQUEOS ORTOPEDIA Y TRAUMATOLOG\u00cdA:"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":3765,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3778","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ortopedia &amp; Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso<\/title>\n<meta name=\"description\" content=\"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ortopedia &amp; Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso\" \/>\n<meta property=\"og:description\" content=\"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Clinica Picasso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clinicapicasso\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T09:20:42+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/ortopedia-y-traumatologia\\\/\",\"url\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/ortopedia-y-traumatologia\\\/\",\"name\":\"Ortopedia & Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#website\"},\"datePublished\":\"2016-05-25T11:55:06+00:00\",\"dateModified\":\"2026-05-07T09:20:42+00:00\",\"description\":\"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/ortopedia-y-traumatologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/ortopedia-y-traumatologia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/ortopedia-y-traumatologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHEQUEOS\",\"item\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/es\\\/chequeos-medicos-mallorca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHEQUEOS ORTOPEDIA Y TRAUMATOLOG\u00cdA:\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/\",\"name\":\"Clinica Picasso\",\"description\":\"Arzt Klinik Mallorca - in unserem Internationalen Facharzt-Zentrum finden Sie u.a.: Chirurg, Kinderarzt, Urologe, Psychologe, Zahnarzt, Dermatologe, Urologe, HNO, Orthop\u00e4de, Neurologe, Psychotherapeut...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#organization\",\"name\":\"Clinica Picasso\",\"url\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/clipic-logo-only-2.webp\",\"contentUrl\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/clipic-logo-only-2.webp\",\"width\":162,\"height\":210,\"caption\":\"Clinica Picasso\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clinica-picasso.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clinicapicasso\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJpffO0lLskkoFyPgbzQlcA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ortopedia & Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso","description":"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/","og_locale":"es_ES","og_type":"article","og_title":"Ortopedia & Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso","og_description":"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.","og_url":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/","og_site_name":"Clinica Picasso","article_publisher":"https:\/\/www.facebook.com\/clinicapicasso\/","article_modified_time":"2026-05-07T09:20:42+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/","url":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/","name":"Ortopedia & Traumatolog\u00eda - Chequeos M\u00e9dicos Cl\u00ednica Picasso","isPartOf":{"@id":"https:\/\/www.clinica-picasso.eu\/#website"},"datePublished":"2016-05-25T11:55:06+00:00","dateModified":"2026-05-07T09:20:42+00:00","description":"Chequeos m\u00e9dicos de ortopedia y traumatolog\u00eda realizado por expertos en Cl\u00ednica Picasso en Mallorca. Prevenga enfermedades y cuide su salud.","breadcrumb":{"@id":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/ortopedia-y-traumatologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.clinica-picasso.eu\/es\/"},{"@type":"ListItem","position":2,"name":"CHEQUEOS","item":"https:\/\/www.clinica-picasso.eu\/es\/chequeos-medicos-mallorca\/"},{"@type":"ListItem","position":3,"name":"CHEQUEOS ORTOPEDIA Y TRAUMATOLOG\u00cdA:"}]},{"@type":"WebSite","@id":"https:\/\/www.clinica-picasso.eu\/#website","url":"https:\/\/www.clinica-picasso.eu\/","name":"Clinica Picasso","description":"Arzt Klinik Mallorca - in unserem Internationalen Facharzt-Zentrum finden Sie u.a.: Chirurg, Kinderarzt, Urologe, Psychologe, Zahnarzt, Dermatologe, Urologe, HNO, Orthop\u00e4de, Neurologe, Psychotherapeut...","publisher":{"@id":"https:\/\/www.clinica-picasso.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinica-picasso.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinica-picasso.eu\/#organization","name":"Clinica Picasso","url":"https:\/\/www.clinica-picasso.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinica-picasso.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.clinica-picasso.eu\/wp-content\/uploads\/2025\/09\/clipic-logo-only-2.webp","contentUrl":"https:\/\/www.clinica-picasso.eu\/wp-content\/uploads\/2025\/09\/clipic-logo-only-2.webp","width":162,"height":210,"caption":"Clinica Picasso"},"image":{"@id":"https:\/\/www.clinica-picasso.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clinicapicasso\/","https:\/\/www.youtube.com\/channel\/UCJpffO0lLskkoFyPgbzQlcA"]}]}},"_links":{"self":[{"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/pages\/3778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/comments?post=3778"}],"version-history":[{"count":1,"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/pages\/3778\/revisions"}],"predecessor-version":[{"id":7141,"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/pages\/3778\/revisions\/7141"}],"up":[{"embeddable":true,"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/pages\/3765"}],"wp:attachment":[{"href":"https:\/\/www.clinica-picasso.eu\/es\/wp-json\/wp\/v2\/media?parent=3778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}